{"id":1854,"date":"2024-09-07T13:39:39","date_gmt":"2024-09-07T13:39:39","guid":{"rendered":"https:\/\/www.pacgrafica.com\/blog\/?p=1854"},"modified":"2024-09-07T13:45:37","modified_gmt":"2024-09-07T13:45:37","slug":"frases","status":"publish","type":"post","link":"https:\/\/www.pacgrafica.com\/blog\/frases\/","title":{"rendered":"frases"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1854\" class=\"elementor elementor-1854\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc62a99 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"fc62a99\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3923b78\" data-id=\"3923b78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e21bd6 elementor-widget elementor-widget-heading\" data-id=\"6e21bd6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Algunos pensamientos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f54bbd1\" data-id=\"f54bbd1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-accf009 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"accf009\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5f408f3\" data-id=\"5f408f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79b0b4a elementor-widget elementor-widget-text-editor\" data-id=\"79b0b4a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El acceso a las redes sociales es una manera de instruirse, a pesar que hay mucho fake news la responsabilidad de los sistemas debe preentrenar al algoritmo para aceptar la justicia del pueblo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-90ffef1\" data-id=\"90ffef1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88964e6 elementor-widget elementor-widget-text-editor\" data-id=\"88964e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Miniaturas profe jlopez designer 50%<\/li><li>Logotipos Guti\u00e9rrez Comercios 25%<\/li><li>Talentic Reuniones\u00a0<\/li><li>Dentello 0%<\/li><li>MC Tires 5%<\/li><li>Blog Audio articulos PacGrafica 0%<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-183a089 elementor-widget elementor-widget-text-editor\" data-id=\"183a089\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>aprede yaaaaa!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4b113b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"b4b113b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5083db3\" data-id=\"5083db3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e916059\" data-id=\"e916059\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76e3273 elementor-widget elementor-widget-eael-feature-list\" data-id=\"76e3273\" data-element_type=\"widget\" data-widget_type=\"eael-feature-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"-icon-position-left -tablet-icon-position-left -mobile-icon-position-left\">\n\t\t\t<ul id=\"eael-feature-list-76e3273\" class=\"eael-feature-list-items circle stacked  eael-feature-list-vertical\">\n\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-8c60aaf\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-0\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\">Tarea 1<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">Miniaturas profe jlopez designer 50%<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-c56c527\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-1\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\">Tarea 2<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">Logotipos Guti\u00e9rrez Comercios 25%<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-69d6764\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-2\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-anchor\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\">Tarea 3<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">Talentic Reuniones<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-60552f6\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-3\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\">Tarea 4<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">Dentello 0%<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-32bd62d\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-4\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\">Tarea 5<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">MCTires 5%<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-2cc38b1\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-5\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\">Tarea 6<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">Blog Pac Grafica 5%<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Algunos pensamientos El acceso a las redes sociales es una manera de instruirse, a pesar que hay mucho fake news la responsabilidad de los sistemas debe preentrenar al algoritmo para aceptar la justicia del pueblo Miniaturas profe jlopez designer 50% Logotipos Guti\u00e9rrez Comercios 25% Talentic Reuniones\u00a0 Dentello 0% MC Tires 5% Blog Audio articulos PacGrafica 0% aprede yaaaaa! Tarea 1 Miniaturas profe jlopez designer 50% Tarea 2 Logotipos Guti\u00e9rrez Comercios 25% Tarea 3 Talentic Reuniones Tarea 4 Dentello 0% Tarea 5 MCTires 5% Tarea 6 Blog Pac Grafica 5%<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-1854","post","type-post","status-publish","format-standard","hentry","category-animacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>frases - Blog jlopez<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pacgrafica.com\/blog\/frases\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"frases - Blog jlopez\" \/>\n<meta property=\"og:description\" content=\"Algunos pensamientos El acceso a las redes sociales es una manera de instruirse, a pesar que hay mucho fake news la responsabilidad de los sistemas debe preentrenar al algoritmo para aceptar la justicia del pueblo Miniaturas profe jlopez designer 50% Logotipos Guti\u00e9rrez Comercios 25% Talentic Reuniones\u00a0 Dentello 0% MC Tires 5% Blog Audio articulos PacGrafica 0% aprede yaaaaa! Tarea 1 Miniaturas profe jlopez designer 50% Tarea 2 Logotipos Guti\u00e9rrez Comercios 25% Tarea 3 Talentic Reuniones Tarea 4 Dentello 0% Tarea 5 MCTires 5% Tarea 6 Blog Pac Grafica 5%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pacgrafica.com\/blog\/frases\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog jlopez\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-07T13:39:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-07T13:45:37+00:00\" \/>\n<meta name=\"author\" content=\"jlopez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jlopez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/frases\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/frases\/\"},\"author\":{\"name\":\"jlopez\",\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/person\/5a2185bcfc53c9b659313c13824559a0\"},\"headline\":\"frases\",\"datePublished\":\"2024-09-07T13:39:39+00:00\",\"dateModified\":\"2024-09-07T13:45:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/frases\/\"},\"wordCount\":76,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#organization\"},\"articleSection\":[\"Animaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pacgrafica.com\/blog\/frases\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/frases\/\",\"url\":\"https:\/\/www.pacgrafica.com\/blog\/frases\/\",\"name\":\"frases - Blog jlopez\",\"isPartOf\":{\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#website\"},\"datePublished\":\"2024-09-07T13:39:39+00:00\",\"dateModified\":\"2024-09-07T13:45:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/frases\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pacgrafica.com\/blog\/frases\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/frases\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.pacgrafica.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"frases\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#website\",\"url\":\"https:\/\/www.pacgrafica.com\/blog\/\",\"name\":\"Blog jlopez\",\"description\":\"Contenidos y escritos\",\"publisher\":{\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pacgrafica.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#organization\",\"name\":\"Blog jlopez\",\"url\":\"https:\/\/www.pacgrafica.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pacgrafica.com\/blog\/wp-content\/uploads\/2023\/03\/logo-jlopez-Blog.png\",\"contentUrl\":\"https:\/\/www.pacgrafica.com\/blog\/wp-content\/uploads\/2023\/03\/logo-jlopez-Blog.png\",\"width\":399,\"height\":216,\"caption\":\"Blog jlopez\"},\"image\":{\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/person\/5a2185bcfc53c9b659313c13824559a0\",\"name\":\"jlopez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ac60129f52bf43cdab01f17c1c614493426cd82cde85ab5e45adee63ff026617?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ac60129f52bf43cdab01f17c1c614493426cd82cde85ab5e45adee63ff026617?s=96&d=mm&r=g\",\"caption\":\"jlopez\"},\"sameAs\":[\"https:\/\/www.pacgrafica.com\/blog\"],\"url\":\"https:\/\/www.pacgrafica.com\/blog\/author\/jlopez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"frases - Blog jlopez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pacgrafica.com\/blog\/frases\/","og_locale":"es_ES","og_type":"article","og_title":"frases - Blog jlopez","og_description":"Algunos pensamientos El acceso a las redes sociales es una manera de instruirse, a pesar que hay mucho fake news la responsabilidad de los sistemas debe preentrenar al algoritmo para aceptar la justicia del pueblo Miniaturas profe jlopez designer 50% Logotipos Guti\u00e9rrez Comercios 25% Talentic Reuniones\u00a0 Dentello 0% MC Tires 5% Blog Audio articulos PacGrafica 0% aprede yaaaaa! Tarea 1 Miniaturas profe jlopez designer 50% Tarea 2 Logotipos Guti\u00e9rrez Comercios 25% Tarea 3 Talentic Reuniones Tarea 4 Dentello 0% Tarea 5 MCTires 5% Tarea 6 Blog Pac Grafica 5%","og_url":"https:\/\/www.pacgrafica.com\/blog\/frases\/","og_site_name":"Blog jlopez","article_published_time":"2024-09-07T13:39:39+00:00","article_modified_time":"2024-09-07T13:45:37+00:00","author":"jlopez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jlopez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pacgrafica.com\/blog\/frases\/#article","isPartOf":{"@id":"https:\/\/www.pacgrafica.com\/blog\/frases\/"},"author":{"name":"jlopez","@id":"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/person\/5a2185bcfc53c9b659313c13824559a0"},"headline":"frases","datePublished":"2024-09-07T13:39:39+00:00","dateModified":"2024-09-07T13:45:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pacgrafica.com\/blog\/frases\/"},"wordCount":76,"commentCount":0,"publisher":{"@id":"https:\/\/www.pacgrafica.com\/blog\/#organization"},"articleSection":["Animaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pacgrafica.com\/blog\/frases\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pacgrafica.com\/blog\/frases\/","url":"https:\/\/www.pacgrafica.com\/blog\/frases\/","name":"frases - Blog jlopez","isPartOf":{"@id":"https:\/\/www.pacgrafica.com\/blog\/#website"},"datePublished":"2024-09-07T13:39:39+00:00","dateModified":"2024-09-07T13:45:37+00:00","breadcrumb":{"@id":"https:\/\/www.pacgrafica.com\/blog\/frases\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pacgrafica.com\/blog\/frases\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pacgrafica.com\/blog\/frases\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.pacgrafica.com\/blog\/"},{"@type":"ListItem","position":2,"name":"frases"}]},{"@type":"WebSite","@id":"https:\/\/www.pacgrafica.com\/blog\/#website","url":"https:\/\/www.pacgrafica.com\/blog\/","name":"Blog jlopez","description":"Contenidos y escritos","publisher":{"@id":"https:\/\/www.pacgrafica.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pacgrafica.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.pacgrafica.com\/blog\/#organization","name":"Blog jlopez","url":"https:\/\/www.pacgrafica.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.pacgrafica.com\/blog\/wp-content\/uploads\/2023\/03\/logo-jlopez-Blog.png","contentUrl":"https:\/\/www.pacgrafica.com\/blog\/wp-content\/uploads\/2023\/03\/logo-jlopez-Blog.png","width":399,"height":216,"caption":"Blog jlopez"},"image":{"@id":"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/person\/5a2185bcfc53c9b659313c13824559a0","name":"jlopez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pacgrafica.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ac60129f52bf43cdab01f17c1c614493426cd82cde85ab5e45adee63ff026617?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac60129f52bf43cdab01f17c1c614493426cd82cde85ab5e45adee63ff026617?s=96&d=mm&r=g","caption":"jlopez"},"sameAs":["https:\/\/www.pacgrafica.com\/blog"],"url":"https:\/\/www.pacgrafica.com\/blog\/author\/jlopez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/posts\/1854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/comments?post=1854"}],"version-history":[{"count":4,"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/posts\/1854\/revisions"}],"predecessor-version":[{"id":1858,"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/posts\/1854\/revisions\/1858"}],"wp:attachment":[{"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/media?parent=1854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/categories?post=1854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pacgrafica.com\/blog\/wp-json\/wp\/v2\/tags?post=1854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}